{"id":519,"date":"2022-08-09T12:42:26","date_gmt":"2022-08-09T11:42:26","guid":{"rendered":"https:\/\/conscasablanca.esteri.it\/news\/dal_consolato\/2022\/08\/novita-appuntamento-unico-per-matrimonio\/"},"modified":"2022-08-09T12:42:26","modified_gmt":"2022-08-09T11:42:26","slug":"novita-appuntamento-unico-per-matrimonio","status":"publish","type":"post","link":"https:\/\/conscasablanca.esteri.it\/it\/news\/dal_consolato\/2022\/08\/novita-appuntamento-unico-per-matrimonio\/","title":{"rendered":"NOVITA&#8217;: APPUNTAMENTO UNICO PER MATRIMONIO (STATO CIVILE E VISTI)"},"content":{"rendered":"<p>Da oggi \u00e8 disponibile un <strong>nuovo servizio<\/strong> che semplifica la procedura e riduce i tempi per i matrimoni tra cittadini italiani e marocchini che si celebrano in Marocco.<\/p>\n<p>E\u2019 infatti gi\u00e0 da questo momento prenotabile (prima data disponibile 1 settembre) un <strong>appuntamento unificato<\/strong> per per i matrimoni che hanno avuto luogo dopo il 1 giugno 2022.<\/p>\n<p>Il nuovo appuntamento funziona cos\u00ec:<\/p>\n<p>1) Occorre <strong>collegarsi sul portale\u00a0<\/strong><a href=\"https:\/\/prenotami.esteri.it\/\">Prenot@mi<\/a> e selezionare APPUNTAMENTO UNIFICATO MATRIMONIO (trascrizione atto di matrimonio e visto per congiunto cittadino UE). Vedi la schermata sotto:<\/p>\n<p><img decoding=\"async\" src=\"resource\/img\/2022\/08\/appuntamento_unico2.png\" alt=\"appuntamento unico2\" \/><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>2) Il giorno dell\u2019appuntamento, <strong>il richiedente si presenta presso il Consolato Generale d\u2019Italia a Casablanca<\/strong> per la registrazione dell\u2019atto di matrimonio (debitamente tradotto e apostillato)<\/p>\n<p><strong>ATTENZIONE: non si pu\u00f2 accedere all&#8217;appuntamento unico quando l&#8217;atto di matrimonio \u00e8 gi\u00e0 stato registrato presso il Comune: in tal caso, la procedura \u00e8 quella di semplice richiesta di visto per ricongiungimento, da espletare secondo le consuete procedure indicate\u00a0<a href=\"it\/la_comunicazione\/dal_consolato\/2023\/01\/avviso-prossimo-cambio-nella-gestione.html\">qui<\/a> .<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>3) <strong>Lo stesso giorno<\/strong> il\/la richiedente deposita presso il Consolato Generale i documenti per la richiesta di visto (che dovr\u00e0 avere con s\u00e9)<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>CONDIZIONI PER L&#8217;OTTENIMENTO DELL&#8217;APPUNTAMENTO UNIFICATO PER MATRIMONIO<\/strong> (trascrizione atto di matrimonio e contestuale richiesta visto per congiunto cittadino UE):<\/p>\n<p>1) Il matrimonio deve essere tra cittadino\/a italiano\/a e cittadino\/a marocchino\/a <strong>celebrato dopo il 1 giugno 2022<\/strong> (fa fede la data del matrimonio o la data di rilascio della capacit\u00e0 matrimoniale)<\/p>\n<p>2) La documentazione <strong>deve essere completa<\/strong> (atto di matrimonio tradotto e apostillato), altrimenti decade il diritto all&#8217;appuntamento lo stesso giorno per il visto<\/p>\n<p>3) L&#8217;appuntamento per il visto \u00e8 fissato <strong>lo stesso giorno ed \u00e8 nominativo, non \u00e8 rinviabile n\u00e9 trasferibile<\/strong><\/p>\n<p>4) Il rilascio del visto \u00e8 condizionato alla <strong>verifica e all&#8217;effettiva trascrizione<\/strong> dell&#8217;atto di matrimonio da parte del Comune di residenza del congiunto italiano<\/p>\n<p>5) Il deposito del visto presso l&#8217;outsourcer \u00e8 soggetto a tariffa amministrativa stabilita in autonomia dall&#8217;outsourcer stesso e pagabile direttamente presso l&#8217;agenzia<\/p>\n<p>6) Verr\u00e0 fatta capillare verifica degli appuntamenti occupati da intermediari, nel qual caso, <strong>gli stessi appuntamenti verranno sistematicamente annullati<\/strong>. <strong><span style=\"text-decoration: underline;\">E&#8217; essenziale indicare correttamente sul portale, a tal fine, il corretto numero di telefono al quale il richiedente \u00e8 raggiungibile.<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"Da oggi \u00e8 disponibile un nuovo servizio che semplifica la procedura e riduce i tempi per i matrimoni tra cittadini italiani e marocchini che si celebrano in Marocco. E\u2019 infatti gi\u00e0 da questo momento prenotabile (prima data disponibile 1 settembre) un appuntamento unificato per per i matrimoni che hanno avuto luogo dopo il 1 giugno [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-519","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conscasablanca.esteri.it\/it\/wp-json\/wp\/v2\/posts\/519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscasablanca.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscasablanca.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscasablanca.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscasablanca.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=519"}],"version-history":[{"count":0,"href":"https:\/\/conscasablanca.esteri.it\/it\/wp-json\/wp\/v2\/posts\/519\/revisions"}],"wp:attachment":[{"href":"https:\/\/conscasablanca.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=519"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscasablanca.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}